{"id":2327,"date":"2023-02-19T21:08:17","date_gmt":"2023-02-19T20:08:17","guid":{"rendered":"http:\/\/khaledosman.fr\/blog\/?p=2327"},"modified":"2025-01-12T16:09:14","modified_gmt":"2025-01-12T15:09:14","slug":"voir-lhay-les-roses-et-mourir","status":"publish","type":"post","link":"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/voir-lhay-les-roses-et-mourir\/","title":{"rendered":"Voir l&rsquo;Ha\u00ff-les-roses et mourir"},"content":{"rendered":"<p>Hier, je suis arriv\u00e9 au salon de L&rsquo;Ha\u00ff-les-roses, pour d\u00e9couvrir que les exemplaires de mon roman, eux, ne le sont pas (arriv\u00e9s). L&rsquo;organisatrice, tr\u00e8s courtoise, se r\u00e9pand en excuses, assume pleinement la responsabilit\u00e9 de ce manquement dont elle refuse de rejeter la faute sur tout autre qu&rsquo;elle. Je suis d&rsquo;autant plus ennuy\u00e9 qu&rsquo;un \u00ab\u00a0caf\u00e9 litt\u00e9raire\u00a0\u00bb est pr\u00e9vu avec moi quelques heures plus tard &#8211; nous parlerions donc d&rsquo;un livre que les lecteurs int\u00e9ress\u00e9s (le cas \u00e9ch\u00e9ant) ne pourraient se faire ensuite d\u00e9dicacer sur le salon.<\/p>\n<p>Il y a bien une solution: faire un aller-retour chez moi pour y prendre mes exemplaires auteur&#8230; Arriv\u00e9 \u00e0 domicile, cependant, l&rsquo;id\u00e9e de retourner l\u00e0-bas avec mes livres sous le bras m&rsquo;appara\u00eet soudain d\u00e9risoire; \u00e0 la maison, mon jeune entourage ne&#8230; m&rsquo;encourage pas plus que \u00e7a: \u00ab\u00a0N&rsquo;y va pas, c&rsquo;est trop la honte!\u00a0\u00bb &#x1f609;<br \/>\nComme je rappelle l&rsquo;organisatrice pour lui dire que je ne pense pas revenir, une phrase dans son propos m&rsquo;interpelle: \u00ab\u00a0Je vous comprends, bien s\u00fbr&#8230; c&rsquo;est juste un peu dommage pour la biblioth\u00e9caire qui avait travaill\u00e9 sur votre roman&#8230;\u00a0\u00bb<\/p>\n<p>Bref, j&rsquo;y suis retourn\u00e9, et je ne l&rsquo;ai pas regrett\u00e9. Car \u00ab\u00a0l&rsquo;air de rien\u00a0\u00bb, ladite biblioth\u00e9caire de L&rsquo;Ha\u00ff avait pr\u00e9par\u00e9 tr\u00e8s scrupuleusement cette rencontre. Elle a pr\u00e9sent\u00e9 le roman, r\u00e9sumant l&rsquo;intrigue en prenant soin de ne pas r\u00e9v\u00e9ler le d\u00e9nouement, a su mettre en lumi\u00e8re les diff\u00e9rentes dimensions du roman sans en manquer aucune, a fait part (de mani\u00e8re \u00e9logieuse mais l\u00e0 n&rsquo;est pas mon propos) des \u00e9motions qu&rsquo;elle avait ressenties \u00e0 la lecture et qu&rsquo;elle souhaitait partager avec l&rsquo;assistance (clairsem\u00e9e mais l\u00e0 n&rsquo;est pas mon propos). Chacune de ses r\u00e9flexions amenait une question pertinente. En un mot, on ne m&rsquo;avait jamais parl\u00e9 (et amen\u00e9 \u00e0 parler) de mon roman comme \u00e7a. Respect.<\/p>\n<p>Copyright Khaled Osman<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, je suis arriv\u00e9 au salon de L&rsquo;Ha\u00ff-les-roses, pour d\u00e9couvrir que les exemplaires de mon roman, eux, ne le sont pas (arriv\u00e9s). L&rsquo;organisatrice, tr\u00e8s courtoise, se r\u00e9pand en excuses, assume pleinement la responsabilit\u00e9 de ce manquement dont elle refuse de&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/voir-lhay-les-roses-et-mourir\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[91,122],"class_list":["post-2327","post","type-post","status-publish","format-standard","hentry","category-litterature","tag-khaled-osman-auteur","tag-le-caire-a-corps-perdu"],"_links":{"self":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/comments?post=2327"}],"version-history":[{"count":2,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2327\/revisions"}],"predecessor-version":[{"id":3242,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2327\/revisions\/3242"}],"wp:attachment":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/media?parent=2327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/categories?post=2327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/tags?post=2327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}