{"id":2331,"date":"2023-02-19T21:36:03","date_gmt":"2023-02-19T20:36:03","guid":{"rendered":"http:\/\/khaledosman.fr\/blog\/?p=2331"},"modified":"2023-02-22T16:58:56","modified_gmt":"2023-02-22T15:58:56","slug":"2331","status":"publish","type":"post","link":"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/2331\/","title":{"rendered":"Allez chef, hop!"},"content":{"rendered":"<p><strong>Entendu hier, dans les \u00ab\u00a0Rendez-vous\u00a0\u00bb de Laurent Goumarre sur France-Culture, l&rsquo;entretien passionnant avec le chef-op\u00e9rateur Philippe Rousselot [une vraie l\u00e9gende du m\u00e9tier puisqu&rsquo;il a travaill\u00e9 avec les plus grands noms du cin\u00e9ma, de Tim Burton \u00e0 Alain Cavalier, en passant par Stephen Frears ou Milos Forman] (extraits):<\/strong><br \/>\n<strong>\u00ab\u00a0Pourquoi avez-vous choisi d&rsquo;ouvrir et de refermer votre livre de souvenirs par cette photographie d&rsquo;un pont en Louisiane?<\/strong><br \/>\n<strong>&#8211; En fait, j&rsquo;\u00e9tais l\u00e0 pour un projet, et en y allant tous les matins, je me suis rendu compte que, sur le trajet, je travaillais d\u00e9j\u00e0: je m\u00e9morisais la lumi\u00e8re \u00e9clairant ce pont pr\u00e8s du lac Pontchartrain &#8211; cette lumi\u00e8re qui chaque matin \u00e9tait diff\u00e9rente&#8230; C&rsquo;est ainsi: un chef-op emmagasine tout le temps ces effets de lumi\u00e8re, pour tenter plus tard de les restituer.<\/strong><br \/>\n<strong>&#8211; Au cours de votre carri\u00e8re, vous a-t-on parfois demand\u00e9 des choses inhabituelles?<\/strong><br \/>\n<strong>&#8211; Bien s\u00fbr, souvent. Mais l\u00e0 o\u00f9 j&rsquo;ai radicalement chang\u00e9 ma fa\u00e7on de concevoir mon m\u00e9tier &#8211; avant, je pensais que les choses devaient se faire dans un certain ordre -, c&rsquo;est apr\u00e8s avoir travaill\u00e9 avec Patrice Ch\u00e9reau [pour lequel il a \u00e9clair\u00e9 \u00ab\u00a0La reine Margot\u00a0\u00bb]. Un jour, on devait faire la fameuse sc\u00e8ne du mariage. Donc, je demande \u00e0 Ch\u00e9reau: \u00ab\u00a0O\u00f9 comptez-vous placer la cam\u00e9ra? &#8211; Oh, je ne sais pas encore, me r\u00e9pond-il, \u00e9clairez donc toute la cath\u00e9drale, et puis je verrai en fonction&#8230;\u00a0\u00bb Dans ces cas-l\u00e0, commente doucement Philippe Rousselot, on se dit: \u00ab\u00a0Je l&rsquo;\u00e9trangle tout de suite, ou bien je souris?\u00a0\u00bb Mais on n&rsquo;\u00e9trangle pas quelqu&rsquo;un qu&rsquo;on aime. Alors je lui ai souri, et finalement, j&rsquo;ai \u00e9clair\u00e9 la cath\u00e9drale et lui a pu placer sa cam\u00e9ra&#8230;\u00a0\u00bb<\/strong><\/p>\n<p><strong>Quand l&rsquo;actualit\u00e9 est un peu sombre, \u00e7a fait du bien d&rsquo;entendre quelqu&rsquo;un parler si joliment de lumi\u00e8re&#8230;<\/strong><\/p>\n<p><strong>Copyright Khaled Osman (octobre 2013)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entendu hier, dans les \u00ab\u00a0Rendez-vous\u00a0\u00bb de Laurent Goumarre sur France-Culture, l&rsquo;entretien passionnant avec le chef-op\u00e9rateur Philippe Rousselot [une vraie l\u00e9gende du m\u00e9tier puisqu&rsquo;il a travaill\u00e9 avec les plus grands noms du cin\u00e9ma, de Tim Burton \u00e0 Alain Cavalier, en passant&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/2331\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[124,174],"class_list":["post-2331","post","type-post","status-publish","format-standard","hentry","category-cinema","tag-patrice-chereau","tag-philippe-rousselot"],"_links":{"self":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":0,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}