{"id":2373,"date":"2023-02-19T23:19:29","date_gmt":"2023-02-19T22:19:29","guid":{"rendered":"http:\/\/khaledosman.fr\/blog\/?p=2373"},"modified":"2023-02-20T00:09:37","modified_gmt":"2023-02-19T23:09:37","slug":"un-temps-de","status":"publish","type":"post","link":"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/un-temps-de\/","title":{"rendered":"Un temps de&#8230;"},"content":{"rendered":"<p>Entendu sur France-Inter, Jo\u00ebl Collado, d\u00e9crivant ainsi la m\u00e9t\u00e9o du jour:<\/p>\n<p>\u00ab\u00a0Aujourd&rsquo;hui, le temps se teinte d&rsquo;un aspect automnal.\u00a0\u00bb<\/p>\n<p>Encore un des signes de cette propension des personnes bien inform\u00e9es \u00e0 m\u00e9nager la sensibilit\u00e9 de leurs auditeurs en les endormant par un po\u00e8me \u00e9crit sous LSD plut\u00f4t que de leur dire simplement la v\u00e9rit\u00e9, \u00e0 savoir qu&rsquo;il fait tout bonnement&#8230; un temps de merde.<\/p>\n<p>Copyright Khaled Osman (mai 2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entendu sur France-Inter, Jo\u00ebl Collado, d\u00e9crivant ainsi la m\u00e9t\u00e9o du jour: \u00ab\u00a0Aujourd&rsquo;hui, le temps se teinte d&rsquo;un aspect automnal.\u00a0\u00bb Encore un des signes de cette propension des personnes bien inform\u00e9es \u00e0 m\u00e9nager la sensibilit\u00e9 de leurs auditeurs en les endormant&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.khaledosman.fr\/blog\/2023\/02\/un-temps-de\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2373","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/comments?post=2373"}],"version-history":[{"count":0,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/posts\/2373\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/media?parent=2373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/categories?post=2373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaledosman.fr\/blog\/wp-json\/wp\/v2\/tags?post=2373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}